{"id":1667,"date":"2021-08-17T21:58:51","date_gmt":"2021-08-18T01:58:51","guid":{"rendered":"https:\/\/kippindy.org\/schools\/kipp-indy-college-prep-middle\/"},"modified":"2022-07-25T20:06:51","modified_gmt":"2022-07-25T20:06:51","slug":"kipp-indy-college-prep-middle","status":"publish","type":"page","link":"https:\/\/kippindy.org\/es\/schools\/kipp-indy-college-prep-middle\/","title":{"rendered":"KIPP Indy College Prep Middle"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":1652,"menu_order":32,"comment_status":"closed","ping_status":"closed","template":"page-blocks.php","meta":{"_acf_changed":false,"content-type":"","om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-1667","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KIPP Indy College Prep Middle | Escuelas P\u00fablicas KIPP Indy<\/title>\n<meta name=\"description\" content=\"Universidad, carrera profesional y m\u00e1s.Busca los datos de inscripci\u00f3n, las ofertas acad\u00e9micas, las actividades estudiantiles, testimonios, y m\u00e1s.\u00a1Reg\u00edstrate hoy!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kippindy.org\/es\/schools\/kipp-indy-college-prep-middle\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KIPP Indy College Prep Middle | Escuelas P\u00fablicas KIPP Indy\" \/>\n<meta property=\"og:description\" content=\"Universidad, carrera profesional y m\u00e1s.Busca los datos de inscripci\u00f3n, las ofertas acad\u00e9micas, las actividades estudiantiles, testimonios, y m\u00e1s.\u00a1Reg\u00edstrate hoy!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kippindy.org\/es\/schools\/kipp-indy-college-prep-middle\/\" \/>\n<meta property=\"og:site_name\" content=\"KIPP Indy Public Schools\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-25T20:06:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kippindy.org\\\/es\\\/schools\\\/kipp-indy-college-prep-middle\\\/\",\"url\":\"https:\\\/\\\/kippindy.org\\\/es\\\/schools\\\/kipp-indy-college-prep-middle\\\/\",\"name\":\"KIPP Indy College Prep Middle | Escuelas P\u00fablicas KIPP Indy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kippindy.org\\\/es\\\/#website\"},\"datePublished\":\"2021-08-18T01:58:51+00:00\",\"dateModified\":\"2022-07-25T20:06:51+00:00\",\"description\":\"Universidad, carrera profesional y m\u00e1s.Busca los datos de inscripci\u00f3n, las ofertas acad\u00e9micas, las actividades estudiantiles, testimonios, y m\u00e1s.\u00a1Reg\u00edstrate hoy!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kippindy.org\\\/es\\\/schools\\\/kipp-indy-college-prep-middle\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kippindy.org\\\/es\\\/schools\\\/kipp-indy-college-prep-middle\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kippindy.org\\\/es\\\/schools\\\/kipp-indy-college-prep-middle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kippindy.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Escuelas\",\"item\":\"https:\\\/\\\/kippindy.org\\\/es\\\/schools\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"KIPP Indy College Prep Middle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kippindy.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kippindy.org\\\/es\\\/\",\"name\":\"KIPP Indy Public Schools\",\"description\":\"Together, a future without limits.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kippindy.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KIPP Indy College Prep Middle | Escuelas P\u00fablicas KIPP Indy","description":"Universidad, carrera profesional y m\u00e1s.Busca los datos de inscripci\u00f3n, las ofertas acad\u00e9micas, las actividades estudiantiles, testimonios, y m\u00e1s.\u00a1Reg\u00edstrate hoy!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kippindy.org\/es\/schools\/kipp-indy-college-prep-middle\/","og_locale":"es_ES","og_type":"article","og_title":"KIPP Indy College Prep Middle | Escuelas P\u00fablicas KIPP Indy","og_description":"Universidad, carrera profesional y m\u00e1s.Busca los datos de inscripci\u00f3n, las ofertas acad\u00e9micas, las actividades estudiantiles, testimonios, y m\u00e1s.\u00a1Reg\u00edstrate hoy!","og_url":"https:\/\/kippindy.org\/es\/schools\/kipp-indy-college-prep-middle\/","og_site_name":"KIPP Indy Public Schools","article_modified_time":"2022-07-25T20:06:51+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kippindy.org\/es\/schools\/kipp-indy-college-prep-middle\/","url":"https:\/\/kippindy.org\/es\/schools\/kipp-indy-college-prep-middle\/","name":"KIPP Indy College Prep Middle | Escuelas P\u00fablicas KIPP Indy","isPartOf":{"@id":"https:\/\/kippindy.org\/es\/#website"},"datePublished":"2021-08-18T01:58:51+00:00","dateModified":"2022-07-25T20:06:51+00:00","description":"Universidad, carrera profesional y m\u00e1s.Busca los datos de inscripci\u00f3n, las ofertas acad\u00e9micas, las actividades estudiantiles, testimonios, y m\u00e1s.\u00a1Reg\u00edstrate hoy!","breadcrumb":{"@id":"https:\/\/kippindy.org\/es\/schools\/kipp-indy-college-prep-middle\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kippindy.org\/es\/schools\/kipp-indy-college-prep-middle\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kippindy.org\/es\/schools\/kipp-indy-college-prep-middle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kippindy.org\/es\/"},{"@type":"ListItem","position":2,"name":"Escuelas","item":"https:\/\/kippindy.org\/es\/schools\/"},{"@type":"ListItem","position":3,"name":"KIPP Indy College Prep Middle"}]},{"@type":"WebSite","@id":"https:\/\/kippindy.org\/es\/#website","url":"https:\/\/kippindy.org\/es\/","name":"KIPP Indy Public Schools","description":"Together, a future without limits.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kippindy.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/kippindy.org\/es\/wp-json\/wp\/v2\/pages\/1667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kippindy.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kippindy.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kippindy.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kippindy.org\/es\/wp-json\/wp\/v2\/comments?post=1667"}],"version-history":[{"count":2,"href":"https:\/\/kippindy.org\/es\/wp-json\/wp\/v2\/pages\/1667\/revisions"}],"predecessor-version":[{"id":1898,"href":"https:\/\/kippindy.org\/es\/wp-json\/wp\/v2\/pages\/1667\/revisions\/1898"}],"up":[{"embeddable":true,"href":"https:\/\/kippindy.org\/es\/wp-json\/wp\/v2\/pages\/1652"}],"wp:attachment":[{"href":"https:\/\/kippindy.org\/es\/wp-json\/wp\/v2\/media?parent=1667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}